{"id":8087,"date":"2025-05-20T00:05:47","date_gmt":"2025-05-20T03:05:47","guid":{"rendered":"https:\/\/www.comunicarmais.com.br\/site\/?p=8087"},"modified":"2025-05-20T00:07:45","modified_gmt":"2025-05-20T03:07:45","slug":"stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica","status":"publish","type":"post","link":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/","title":{"rendered":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica"},"content":{"rendered":"\n<p><strong>Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1066\" height=\"813\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06.jpeg\" alt=\"\" class=\"wp-image-8088 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06.jpeg 1066w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1024x781.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-768x586.jpeg 768w\" data-sizes=\"(max-width: 1066px) 100vw, 1066px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1066px; --smush-placeholder-aspect-ratio: 1066\/813;\" \/><figcaption class=\"wp-element-caption\"><sup>Advogado criminalista Fabiano Pimentel <em>(Divulga\u00e7\u00e3o)<\/em><\/sup><\/figcaption><\/figure>\n\n\n\n<p><strong>Reda\u00e7\u00e3o Mais &#8211;<\/strong> As cortes superiores brasileiras t\u00eam protagonizado transforma\u00e7\u00f5es profundas no Direito Penal e Processual Penal, impactando diretamente advogados, promotores, ju\u00edzes e, principalmente, os cidad\u00e3os. Decis\u00f5es recentes do Supremo Tribunal Federal (STF) e do Superior Tribunal de Justi\u00e7a (STJ) t\u00eam reconfigurado o cen\u00e1rio jur\u00eddico com reflexos que j\u00e1 reverberam da atua\u00e7\u00e3o policial \u00e0 rotina dos f\u00f3runs criminais. Para o advogado criminalista Fabiano Pimentel, professor de Direito Processual Penal da Universidade Federal da Bahia (Ufba) e da Universidade do Estado da Bahia (Uneb), o momento \u00e9 de \u201cefervesc\u00eancia interpretativa\u201d no campo penal.<\/p>\n\n\n\n<p>\u201cVivemos um per\u00edodo de grande tens\u00e3o no Direito Penal. As decis\u00f5es recentes refletem tanto a tentativa de ajustar o sistema aos direitos fundamentais quanto a press\u00e3o social por respostas mais efetivas contra a criminalidade\u201d, afirma Pimentel. Segundo ele, o maior desafio est\u00e1 em \u201cequilibrar garantias e efici\u00eancia\u201d.<\/p>\n\n\n\n<p>Uma das mudan\u00e7as mais emblem\u00e1ticas, segundo o jurista, foi a proibi\u00e7\u00e3o do perfilamento racial em abordagens policiais, reafirmada pelo STF no julgamento do Habeas Corpus 208.240\/SP. \u201cFoi um passo importante contra o racismo estrutural no sistema de justi\u00e7a. A abordagem policial agora precisa estar baseada em ind\u00edcios objetivos \u2014 n\u00e3o mais em ra\u00e7a ou apar\u00eancia\u201d, destaca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"626\" height=\"626\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\" alt=\"\" class=\"wp-image-8089 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 626px; --smush-placeholder-aspect-ratio: 626\/626;\" \/><\/figure>\n\n\n\n<p>Outro ponto pol\u00eamico enfrentado pelas cortes diz respeito ao poder investigat\u00f3rio do Minist\u00e9rio P\u00fablico. Em maio de 2024, o STF consolidou que o MP pode, sim, conduzir investiga\u00e7\u00f5es criminais, desde que observe crit\u00e9rios de controle e transpar\u00eancia. \u201cH\u00e1 uma tentativa de evitar abusos e duplicidades em rela\u00e7\u00e3o ao trabalho das pol\u00edcias judici\u00e1rias\u201d, resume Pimentel.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0s mulheres v\u00edtimas de viol\u00eancia, o STF tamb\u00e9m fez hist\u00f3ria ao vedar, na ADPF n\u00ba 1.107, qualquer men\u00e7\u00e3o \u00e0 vida sexual pregressa da v\u00edtima como forma de desqualifica\u00e7\u00e3o durante o julgamento. \u201c\u00c9 uma vit\u00f3ria no combate \u00e0 revitimiza\u00e7\u00e3o e ao machismo processual\u201d, afirma.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<figure class=\"wp-block-pullquote\"><blockquote><p>Outro julgamento de repercuss\u00e3o foi o que trata do porte de drogas para consumo pessoal, em que a Corte fixou que at\u00e9 40g de maconha ou seis plantas f\u00eameas n\u00e3o configuram crime. \u201cIsso tem o potencial de reduzir significativamente o encarceramento por pequenas quantidades. Mas n\u00e3o \u00e9 uma legaliza\u00e7\u00e3o \u2014 o Congresso ainda precisar\u00e1 legislar sobre isso\u201d, explica.<\/p><\/blockquote><\/figure>\n<\/blockquote>\n<\/div>\n<\/div>\n\n\n\n<p>O advogado tamb\u00e9m cita decis\u00f5es sobre Tribunal do J\u00fari, medidas protetivas da Lei Maria da Penha, confiss\u00e3o extrajudicial e acordo de n\u00e3o persecu\u00e7\u00e3o penal como avan\u00e7os importantes no desenho de um sistema mais racional e justo. \u201cO julgamento da S\u00famula 676 do STJ, por exemplo, veda que ju\u00edzes decretem pris\u00e3o preventiva por iniciativa pr\u00f3pria. \u00c9 o fortalecimento do sistema acusat\u00f3rio e da separa\u00e7\u00e3o de fun\u00e7\u00f5es\u201d, observa.<\/p>\n\n\n\n<p>Diante de tantas mudan\u00e7as, Fabiano Pimentel conclui: \u201c\u00c9 fundamental que os profissionais do Direito acompanhem com aten\u00e7\u00e3o essas decis\u00f5es. Mais do que interpreta\u00e7\u00f5es jur\u00eddicas, elas definem os contornos \u00e9ticos e institucionais do nosso sistema de justi\u00e7a criminal\u201d.<\/p>\n\n\n\n<p>________________________________________________________________________________________________________________<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal<\/p>\n","protected":false},"author":2,"featured_media":8089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[2346,2596,68],"class_list":["post-8087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-direito","tag-oab","tag-stf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais<\/title>\n<meta name=\"description\" content=\"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais\" \/>\n<meta property=\"og:description\" content=\"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicar Mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T03:05:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T03:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicar Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:site\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicar Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/\"},\"author\":{\"name\":\"Comunicar Mais\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"headline\":\"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica\",\"datePublished\":\"2025-05-20T03:05:47+00:00\",\"dateModified\":\"2025-05-20T03:07:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/\"},\"wordCount\":557,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\",\"keywords\":[\"Direito\",\"OAB\",\"STF\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/\",\"name\":\"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\",\"datePublished\":\"2025-05-20T03:05:47+00:00\",\"dateModified\":\"2025-05-20T03:07:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"description\":\"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg\",\"width\":626,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/05\\\/20\\\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"name\":\"Comunicar Mais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\",\"name\":\"Comunicar Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"caption\":\"Comunicar Mais\"},\"description\":\"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.\",\"sameAs\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"https:\\\/\\\/www.facebook.com\\\/comunicarmais\\\/\",\"https:\\\/\\\/www.instagram.com\\\/comunicarmaisba\\\/\",\"https:\\\/\\\/x.com\\\/ComunicarmaisBA\"],\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/author\\\/gerenciador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais","description":"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/","og_locale":"pt_BR","og_type":"article","og_title":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais","og_description":"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal","og_url":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/","og_site_name":"Comunicar Mais","article_publisher":"https:\/\/www.facebook.com\/comunicarmais\/","article_author":"https:\/\/www.facebook.com\/comunicarmais\/","article_published_time":"2025-05-20T03:05:47+00:00","article_modified_time":"2025-05-20T03:07:45+00:00","og_image":[{"width":626,"height":626,"url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg","type":"image\/jpeg"}],"author":"Comunicar Mais","twitter_card":"summary_large_image","twitter_creator":"@ComunicarmaisBA","twitter_site":"@ComunicarmaisBA","twitter_misc":{"Escrito por":"Comunicar Mais","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#article","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/"},"author":{"name":"Comunicar Mais","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"headline":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica","datePublished":"2025-05-20T03:05:47+00:00","dateModified":"2025-05-20T03:07:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/"},"wordCount":557,"commentCount":0,"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg","keywords":["Direito","OAB","STF"],"articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/","url":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/","name":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica - Comunicar Mais","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#primaryimage"},"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg","datePublished":"2025-05-20T03:05:47+00:00","dateModified":"2025-05-20T03:07:45+00:00","author":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"description":"Professor da Ufba e Uneb analisa decis\u00f5es recentes dos tribunais superiores e alerta para mudan\u00e7as importantes na justi\u00e7a criminal","breadcrumb":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#primaryimage","url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg","contentUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-14-at-08.36.06-1.jpeg","width":626,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/05\/20\/stf-e-stj-redesenham-o-direito-penal-brasileiro-com-impacto-direto-na-pratica-juridica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comunicarmais.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"STF e STJ redesenham o Direito Penal brasileiro com impacto direto na pr\u00e1tica jur\u00eddica"}]},{"@type":"WebSite","@id":"https:\/\/www.comunicarmais.com.br\/site\/#website","url":"https:\/\/www.comunicarmais.com.br\/site\/","name":"Comunicar Mais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comunicarmais.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284","name":"Comunicar Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","caption":"Comunicar Mais"},"description":"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.","sameAs":["https:\/\/www.comunicarmais.com.br\/site\/","https:\/\/www.facebook.com\/comunicarmais\/","https:\/\/www.instagram.com\/comunicarmaisba\/","https:\/\/x.com\/ComunicarmaisBA"],"url":"https:\/\/www.comunicarmais.com.br\/site\/author\/gerenciador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/8087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/comments?post=8087"}],"version-history":[{"count":2,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/8087\/revisions"}],"predecessor-version":[{"id":8092,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/8087\/revisions\/8092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media\/8089"}],"wp:attachment":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media?parent=8087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/categories?post=8087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/tags?post=8087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}