{"id":747,"date":"2024-01-18T15:35:00","date_gmt":"2024-01-18T18:35:00","guid":{"rendered":"https:\/\/www.comunicarmais.com.br\/site\/?p=747"},"modified":"2024-01-18T19:10:39","modified_gmt":"2024-01-18T22:10:39","slug":"lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia","status":"publish","type":"post","link":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/","title":{"rendered":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia"},"content":{"rendered":"\n<p><strong>Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1170\" height=\"634\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg\" alt=\"\" class=\"wp-image-748 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg 1170w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL-1024x555.jpg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL-768x416.jpg 768w\" data-sizes=\"(max-width: 1170px) 100vw, 1170px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1170px; --smush-placeholder-aspect-ratio: 1170\/634;\" \/><\/figure>\n\n\n\n<p><strong>Ag\u00eancia Brasil &#8211; <\/strong>O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta quinta-feira (18), um acordo de parceria com o estado da Bahia e com o Senai Cimatec visando a cria\u00e7\u00e3o do Parque Tecnol\u00f3gico Aeroespacial da Bahia. Segundo o Planalto, o parque representa o ingresso do Brasil no mercado aeroespacial, setor que movimentou, em 2023, US$ 807,7 bilh\u00f5es, valor que poder\u00e1 chegar a US$ 1,4 trilh\u00e3o at\u00e9 2032. <\/p>\n\n\n\n<p>Durante a cerim\u00f4nia de assinatura do acordo, Lula disse que far\u00e1 uma s\u00e9rie de viagens pelo Brasil \u201cpara mostrar que coisas boas acontecem nesse pa\u00eds\u201d, a exemplo deste parque que ser\u00e1 instalado em uma \u00e1rea da Base A\u00e9rea de Salvador.<\/p>\n\n\n\n<p>Ainda nesta semana, o presidente visitar\u00e1 Pernambuco, para participar da cerim\u00f4nia de retomada das obras da Refinaria Abreu e Lima, e o Cear\u00e1, onde lan\u00e7ar\u00e1 uma unidade regional do Instituto Tecnol\u00f3gico de Aeron\u00e1utica (ITA).<\/p>\n\n\n\n<p>Fruto de um acordo de coopera\u00e7\u00e3o t\u00e9cnica assinado em outubro, o Parque Tecnol\u00f3gico Aeroespacial da Bahia ser\u00e1, de acordo com o Planalto, um ambiente voltado ao fomento do ensino, \u00e0 realiza\u00e7\u00e3o de pesquisas avan\u00e7adas e \u00e0 promo\u00e7\u00e3o da inova\u00e7\u00e3o no campo aeroespacial, nos campos de engenharia de aeronaves, pesquisa, forma\u00e7\u00e3o acad\u00eamica e m\u00e3o de obra.<\/p>\n\n\n\n<p>A \u00e1rea foi cedida pela Uni\u00e3o ao Senai Cimatec, institui\u00e7\u00e3o que ficar\u00e1 respons\u00e1vel pela gest\u00e3o da unidade. De acordo com o Planalto, as ilhas de atua\u00e7\u00e3o do parque ser\u00e3o divididas em quatro vertentes: Espa\u00e7o, Defesa, Mobilidade A\u00e9rea Avan\u00e7ada e Aeron\u00e1utica Comercial.<\/p>\n\n\n\n<p>Entre as \u00e1reas de estudo a serem implementadas no local est\u00e3o as de sistemas avan\u00e7ados de voo e de controle de tr\u00e1fego a\u00e9reo; sistemas de engenharia aeroespacial, novas tecnologias de energia e propuls\u00e3o e ciberseguran\u00e7a aeroespacial.<\/p>\n\n\n\n<p><strong>Forma\u00e7\u00e3o profissional &#8211; <\/strong>\u201cVir aqui anunciar o lan\u00e7amento desse parque tecnol\u00f3gico n\u00e3o \u00e9 uma coisa qualquer\u201d, disse o presidente. \u201cE vou tamb\u00e9m para Recife para visitar uma refinaria que ficou paralisada durante 14 anos, e que j\u00e1 poderia estar refinando 260 mil barris de petr\u00f3leo por dia. Depois eu vou lan\u00e7ar o ITA no Cear\u00e1. O ITA que fica na cidade de S\u00e3o Jos\u00e9 dos Campos, em S\u00e3o Paulo, \u00e9 um dos mais importantes que temos no Brasil\u201d, acrescentou.<\/p>\n\n\n\n<p>Ao destacar que os benef\u00edcios desses empreendimentos v\u00e3o al\u00e9m da gera\u00e7\u00e3o de conhecimento e riquezas, colaborando tamb\u00e9m para a boa forma\u00e7\u00e3o profissional de muitos brasileiros, Lula disse que os problemas do pa\u00eds na \u00e1rea de educa\u00e7\u00e3o \u00e9 secular, mas ser\u00e1 enfrentado pelo governo. Segundo ele, \u201ca elite brasileira nunca teve a inten\u00e7\u00e3o de educar este povo\u201d.<\/p>\n\n\n\n<p>Prova disso, acrescentou o presidente, \u00e9 o fato de a primeira universidade do pa\u00eds ter sido criada 420 anos ap\u00f3s a chegada dos portugueses. Investimentos em educa\u00e7\u00e3o, disse ele, dar\u00e3o melhores condi\u00e7\u00f5es para o pa\u00eds crescer.<\/p>\n\n\n\n<p><strong>Oportunidades &#8211; <\/strong>Segundo Lula, as chances de crescimento do Brasil s\u00e3o ainda maiores no atual contexto, com o mundo precisando fazer um \u201cesfor\u00e7o gigantesco\u201d para diminuir o aquecimento global. \u201cTemos potencial para resolver esse problema com a chamada energia renov\u00e1vel porque podemos fazer diversos tipos de combust\u00edveis que outros pa\u00edses n\u00e3o conseguem fazer. Inclusive teremos o maior polo de hidrog\u00eanio verde do mundo\u201d, acrescentou.<\/p>\n\n\n\n<p>\u201cMas n\u00e3o queremos apenas produzir hidrog\u00eanio para venda. Queremos ser o grande produtor para que as ind\u00fastrias venham produzir, aqui no Brasil, os seus produtos de forma limpa. Se o mundo quiser diminuir a emiss\u00e3o de g\u00e1s de efeito estufa, o Brasil \u00e9 uma chance [para isso]. Esta \u00e9 uma chance extraordin\u00e1ria que temos. E \u00e9 uma grande chance para o Nordeste\u201d, complementou.<\/p>\n\n\n\n<p><strong>Parque Tecnol\u00f3gico &#8211; <\/strong>O Parque Tecnol\u00f3gico Aeroespacial da Bahia tamb\u00e9m colaborar\u00e1 para esse cen\u00e1rio promissor descrito pelo presidente, segundo o Planalto. Inclusive ele j\u00e1 tem despertado o interesse do setor privado.<\/p>\n\n\n\n<p>Durante a cerim\u00f4nia em Salvador, foram assinados memorandos de parcerias com empresas privadas especializadas na produ\u00e7\u00e3o de equipamentos como ve\u00edculos a\u00e9reos que fazem uso de intelig\u00eancia artificial para voos n\u00e3o tripulados; de hardwares e softwares para entrega de encomendas por meio de drones; bem como de fabricantes de plataformas de altitude elevada para voos n\u00e3o tripulados na estratosfera.<\/p>\n\n\n\n<p>Durante o evento de assinatura, a ministra de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, Luciana Santos, destacou o desenvolvimento de ve\u00edculos n\u00e3o tripulados e de um sat\u00e9lite de observa\u00e7\u00e3o de alta resolu\u00e7\u00e3o para monitoramento e vigil\u00e2ncia de florestas e rios, bem como para prote\u00e7\u00e3o de terra ind\u00edgena, defesa e seguran\u00e7a p\u00fablica.<\/p>\n\n\n\n<p>Luciana Santos destacou tamb\u00e9m o primeiro projeto a ser desenvolvido, que \u00e9 o de criar um sistema de Drone. \u201cIsso j\u00e1 foi, inclusive, assinado aqui. Tudo gra\u00e7as \u00e0 decis\u00e3o logo do presidente Lula, de recompor integralmente o Fundo Nacional de Ci\u00eancia e Tecnologia. Quero real\u00e7ar que isso [a cria\u00e7\u00e3o do parque] significa tamb\u00e9m enfrentamento da desigualdade regional e das assimetrias que existem [no pa\u00eds]\u201d, disse a ministra.<\/p>\n\n\n\n<p><strong>Nova industrializa\u00e7\u00e3o &#8211; <\/strong>Segundo Luciana Santos, a iniciativa beneficiar\u00e1 a intelig\u00eancia brasileira, a produ\u00e7\u00e3o cient\u00edfica de universidades, institutos p\u00fablicos de pesquisa. \u201cEsperamos que isso tudo possa se traduzir em produtos e em inova\u00e7\u00e3o, e que essa produ\u00e7\u00e3o cient\u00edfica possa cada vez mais dialogar com setor produtivo. Isso significa atender \u00e0 agenda da nova industrializa\u00e7\u00e3o; de novas bases tecnol\u00f3gicas\u201d.<\/p>\n\n\n\n<p>A ministra acrescentou que a cadeia da aeroespacial tem repercuss\u00f5es em outras \u00e1reas e em v\u00e1rias cadeias produtivas, pela complexidade tecnol\u00f3gica que enseja. \u201cPor isso, ela tem pacto e impacto muito positivo na educa\u00e7\u00e3o; na forma\u00e7\u00e3o do m\u00e3o de obra especializada; e na gera\u00e7\u00e3o de emprego de alta qualidade. Al\u00e9m disso, reduz a fuga de c\u00e9rebros do pa\u00eds, que \u00e9 tamb\u00e9m um assunto muito grave que a gente precisa enfrentar\u201d, completou<\/p>\n\n\n\n<p>A parceria entre os governos federal e da Bahia para a implementa\u00e7\u00e3o do parque tecnol\u00f3gico prev\u00ea R$ 650 milh\u00f5es em investimentos para constru\u00e7\u00e3o e um \u201cvalor equivalente\u201d em equipamentos e laborat\u00f3rios.<\/p>\n\n\n\n<p>A expectativa \u00e9 de que ele comece a funcionar no primeiro semestre de 2025, com a entrada em opera\u00e7\u00e3o da pista e do p\u00e1tio de aeronaves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial<\/p>\n","protected":false},"author":2,"featured_media":748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[418,415,417,416,414],"class_list":["post-747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia","tag-abreu-e-lima","tag-aeroespacial","tag-ita","tag-lula","tag-senai-cimatec"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais<\/title>\n<meta name=\"description\" content=\"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais\" \/>\n<meta property=\"og:description\" content=\"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicar Mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T18:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T22:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicar Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:site\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicar Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/\"},\"author\":{\"name\":\"Comunicar Mais\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"headline\":\"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia\",\"datePublished\":\"2024-01-18T18:35:00+00:00\",\"dateModified\":\"2024-01-18T22:10:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/\"},\"wordCount\":1096,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/JL.jpg\",\"keywords\":[\"Abreu e Lima\",\"Aeroespacial\",\"ITA\",\"Lula\",\"Senai Cimatec\"],\"articleSection\":[\"Ci\u00eancia &amp; Tecnologia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/\",\"name\":\"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/JL.jpg\",\"datePublished\":\"2024-01-18T18:35:00+00:00\",\"dateModified\":\"2024-01-18T22:10:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"description\":\"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/JL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/JL.jpg\",\"width\":1170,\"height\":634,\"caption\":\"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/18\\\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"name\":\"Comunicar Mais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\",\"name\":\"Comunicar Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"caption\":\"Comunicar Mais\"},\"description\":\"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.\",\"sameAs\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"https:\\\/\\\/www.facebook.com\\\/comunicarmais\\\/\",\"https:\\\/\\\/www.instagram.com\\\/comunicarmaisba\\\/\",\"https:\\\/\\\/x.com\\\/ComunicarmaisBA\"],\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/author\\\/gerenciador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais","description":"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/","og_locale":"pt_BR","og_type":"article","og_title":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais","og_description":"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial","og_url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/","og_site_name":"Comunicar Mais","article_publisher":"https:\/\/www.facebook.com\/comunicarmais\/","article_author":"https:\/\/www.facebook.com\/comunicarmais\/","article_published_time":"2024-01-18T18:35:00+00:00","article_modified_time":"2024-01-18T22:10:39+00:00","og_image":[{"width":1170,"height":634,"url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg","type":"image\/jpeg"}],"author":"Comunicar Mais","twitter_card":"summary_large_image","twitter_creator":"@ComunicarmaisBA","twitter_site":"@ComunicarmaisBA","twitter_misc":{"Escrito por":"Comunicar Mais","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#article","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/"},"author":{"name":"Comunicar Mais","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"headline":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia","datePublished":"2024-01-18T18:35:00+00:00","dateModified":"2024-01-18T22:10:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/"},"wordCount":1096,"commentCount":0,"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg","keywords":["Abreu e Lima","Aeroespacial","ITA","Lula","Senai Cimatec"],"articleSection":["Ci\u00eancia &amp; Tecnologia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/","url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/","name":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia - Comunicar Mais","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#primaryimage"},"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg","datePublished":"2024-01-18T18:35:00+00:00","dateModified":"2024-01-18T22:10:39+00:00","author":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"description":"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial","breadcrumb":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#primaryimage","url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg","contentUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/JL.jpg","width":1170,"height":634,"caption":"Para Planalto, este \u00e9 o ingresso do Brasil no mercado aeroespacial"},{"@type":"BreadcrumbList","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/18\/lula-assina-acordo-para-criacao-de-parque-aeroespacial-na-bahia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comunicarmais.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Lula assina acordo para cria\u00e7\u00e3o de parque aeroespacial na Bahia"}]},{"@type":"WebSite","@id":"https:\/\/www.comunicarmais.com.br\/site\/#website","url":"https:\/\/www.comunicarmais.com.br\/site\/","name":"Comunicar Mais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comunicarmais.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284","name":"Comunicar Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","caption":"Comunicar Mais"},"description":"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.","sameAs":["https:\/\/www.comunicarmais.com.br\/site\/","https:\/\/www.facebook.com\/comunicarmais\/","https:\/\/www.instagram.com\/comunicarmaisba\/","https:\/\/x.com\/ComunicarmaisBA"],"url":"https:\/\/www.comunicarmais.com.br\/site\/author\/gerenciador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"predecessor-version":[{"id":749,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/747\/revisions\/749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media\/748"}],"wp:attachment":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}