{"id":7286,"date":"2025-03-30T13:34:00","date_gmt":"2025-03-30T16:34:00","guid":{"rendered":"https:\/\/www.comunicarmais.com.br\/site\/?p=7286"},"modified":"2025-03-30T16:50:18","modified_gmt":"2025-03-30T19:50:18","slug":"governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao","status":"publish","type":"post","link":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/","title":{"rendered":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o"},"content":{"rendered":"\n<p><strong>Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1433\" height=\"806\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1433x806.jpeg\" alt=\"\" class=\"wp-image-7287 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1433x806.jpeg 1433w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1024x576.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-768x432.jpeg 768w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1536x864.jpeg 1536w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1320x743.jpeg 1320w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg 1600w\" data-sizes=\"(max-width: 1433px) 100vw, 1433px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1433px; --smush-placeholder-aspect-ratio: 1433\/806;\" \/><figcaption class=\"wp-element-caption\"><em><sup>(Foto: Thuane Maria\/GOVBA)<\/sup><\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Reda\u00e7\u00e3o Mais &#8211;<\/strong> Encerrando as agendas de comemora\u00e7\u00f5es pelo anivers\u00e1rio de 476 anos de Salvador, o Governo do Estado levou a Feira Sa\u00fade Mais Perto ao bairro de Cajazeiras, neste domingo (30). Realizada pela Secretaria da Sa\u00fade da Bahia (Sesab) em parceria com as Volunt\u00e1rias Sociais da Bahia (VSBA), o governador Jer\u00f4nimo Rodrigues, acompanhado do ministro da Casa Civil, Rui Costa, al\u00e9m de outras autoridades, visitaram a a\u00e7\u00e3o, que acontece at\u00e9 as 16h, com a oferta de servi\u00e7os de sa\u00fade gratuitos para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>Dentre os servi\u00e7os prestados s\u00e3o oferecidos exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente. A feira tamb\u00e9m oferece servi\u00e7os do SAC M\u00f3vel, como a emiss\u00e3o de 1\u00aa e 2\u00aa vias da Carteira de Identidade. Quem aprovou o servi\u00e7o foi a moradora do Barbalho, Leila Flores, \u201cTrabalho aqui na comunidade Castelo Branco em projetos sociais. E a iniciativa \u00e9 muito importante para a comunidade estar aqui, buscando o servi\u00e7o de forma pr\u00e1tica e f\u00e1cil. Muito importante esse suporte e que possam vir para outras comunidades, outros bairros\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1433\" height=\"955\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-1433x955.jpeg\" alt=\"\" class=\"wp-image-7288 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-1433x955.jpeg 1433w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-1024x682.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-768x512.jpeg 768w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-1536x1023.jpeg 1536w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1-1320x879.jpeg 1320w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1.jpeg 1600w\" data-sizes=\"(max-width: 1433px) 100vw, 1433px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1433px; --smush-placeholder-aspect-ratio: 1433\/955;\" \/><figcaption class=\"wp-element-caption\"><em><sup>(Foto: Thuane Maria\/GOVBA)<\/sup><\/em><\/figcaption><\/figure>\n\n\n\n<p>\u201cUma visita aqui a Feira de Sa\u00fade, que \u00e9 a Sa\u00fade Mais Perto. Uma a\u00e7\u00e3o importante que oferece aos moradores documentos e atendimentos de sa\u00fade\u201d, refor\u00e7ou o governador Jer\u00f4nimo Rodrigues. Para ter acesso aos servi\u00e7os, os interessados devem levar ao local: RG, CPF e Cart\u00e3o do SUS; Certid\u00e3o de Nascimento ou Casamento original (caso precise emitir a 1\u00aa ou 2\u00aa via do RG); Solicita\u00e7\u00e3o m\u00e9dica para ultrassonografia e exames laboratoriais. Menores de idade devem estar acompanhados por um respons\u00e1vel legal. A expectativa, entre s\u00e1bado e domingo, \u00e9 que sejam realizados cerca de 7 mil atendimentos nos dois dias da Feira Sa\u00fade Mais Perto em Cajazeiras.<\/p>\n\n\n\n<p>\u201cPor meio dessas e de outras a\u00e7\u00f5es nesta semana do anivers\u00e1rio de Salvador, reafirmamos o nosso compromisso de cuidar dos baianos. A presen\u00e7a do Governo do Estado na sa\u00fade de Salvador \u00e9 essencial para a popula\u00e7\u00e3o, sobretudo porque ela acontece de forma planejada, cont\u00ednua e estruturante\u201d, avalia a secret\u00e1ria de Sa\u00fade do Estado, Roberta Santana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1433\" height=\"955\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1433x955.jpeg\" alt=\"\" class=\"wp-image-7289 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1433x955.jpeg 1433w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1024x682.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-768x512.jpeg 768w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1536x1023.jpeg 1536w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51-1320x879.jpeg 1320w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.51.jpeg 1600w\" data-sizes=\"(max-width: 1433px) 100vw, 1433px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1433px; --smush-placeholder-aspect-ratio: 1433\/955;\" \/><figcaption class=\"wp-element-caption\"><em><sup>(Foto: Thuane Maria\/GOVBA)<\/sup><\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Ambul\u00e2ncias &#8211; <\/strong>Durante evento neste domingo (30), em Cajazeiras, o governador Jer\u00f4nimo Rodrigues, juntamente com a secret\u00e1ria Roberta Santana, tamb\u00e9m entregou ambul\u00e2ncias para tr\u00eas unidades estaduais de sa\u00fade da capital: Unidade de Emerg\u00eancia de Cajazeiras, Maternidade Albert Sabin e Hospital El\u00e1dio Lasserre. Os ve\u00edculos s\u00e3o do tipo Van-Renault, no valor unit\u00e1rio de R$ 279.067.<\/p>\n\n\n\n<p>Essas tr\u00eas ambul\u00e2ncias se somam a outras cinco entregues pelo Governo do Estado, na \u00faltima ter\u00e7a-feira (25), para o Hospital Geral Roberto Santos (duas unidades), Casa de Apoio \u00e0 Mulher com C\u00e2ncer, Centro Estadual de Oncologia (Cican) e Maternidade Maria da Concei\u00e7\u00e3o de Jesus, como parte do pacote de investimentos em sa\u00fade na semana de anivers\u00e1rio dos 476 anos de Salvador. No total, a gest\u00e3o estadual investiu R$2,23 milh\u00f5es nos novos ve\u00edculos destinados a sete unidades de sa\u00fade da capital baiana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1433\" height=\"955\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-1433x955.jpeg\" alt=\"\" class=\"wp-image-7290 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-1433x955.jpeg 1433w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-1024x682.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-768x512.jpeg 768w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-1536x1023.jpeg 1536w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49-1320x879.jpeg 1320w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.49.jpeg 1600w\" data-sizes=\"(max-width: 1433px) 100vw, 1433px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1433px; --smush-placeholder-aspect-ratio: 1433\/955;\" \/><figcaption class=\"wp-element-caption\"><em><sup>(Foto: Thuane Maria\/GOVBA)<\/sup><\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Outras a\u00e7\u00f5es &#8211; <\/strong>Totalizando R$ 168,9 milh\u00f5es, o pacote de investimentos do Governo do Estado na sa\u00fade de Salvador inclui a moderniza\u00e7\u00e3o do Hospital Geral do Estado (HGE). Com aporte de R$ 118 milh\u00f5es, a unidade ganhar\u00e1 uma nova emerg\u00eancia com 52 leitos, um novo ambulat\u00f3rio adulto e pedi\u00e1trico com 14 salas, al\u00e9m da requalifica\u00e7\u00e3o completa do centro cir\u00fargico. Tamb\u00e9m ser\u00e3o implantados 10 novos leitos de UTI, incluindo uma UTI neurol\u00f3gica com 10 leitos, refor\u00e7ando o cuidado a pacientes cr\u00edticos. A infraestrutura ser\u00e1 ainda aprimorada com a constru\u00e7\u00e3o de um heliponto.<\/p>\n\n\n\n<p>Outro destaque \u00e9 o Centro Estadual de Oncologia (Cican), que ser\u00e1 ampliado com aporte de R$ 26,7 milh\u00f5es. A unidade passar\u00e1 a contar com o primeiro PET Scan do SUS na Bahia e ter\u00e1 ainda uma nova resson\u00e2ncia magn\u00e9tica, hospital-dia, uma recep\u00e7\u00e3o ampliada, al\u00e9m de 13 novos leitos e quatro salas cir\u00fargicas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1433\" height=\"955\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-1433x955.jpeg\" alt=\"\" class=\"wp-image-7291 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-1433x955.jpeg 1433w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-1024x682.jpeg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-768x512.jpeg 768w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-1536x1023.jpeg 1536w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1-1320x879.jpeg 1320w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50-1.jpeg 1600w\" data-sizes=\"(max-width: 1433px) 100vw, 1433px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1433px; --smush-placeholder-aspect-ratio: 1433\/955;\" \/><figcaption class=\"wp-element-caption\"><em><sup>(Foto: Thuane Maria\/GOVBA)<\/sup><\/em><\/figcaption><\/figure>\n\n\n\n<p>No Hospital Geral Roberto Santos (HGRS), est\u00e1 prevista a amplia\u00e7\u00e3o do setor de hemodin\u00e2mica, com a instala\u00e7\u00e3o de nova sala de exames e mais quatro leitos de recupera\u00e7\u00e3o p\u00f3s-anest\u00e9sica (RPA). O investimento de R$ 8,7 milh\u00f5es contempla a aquisi\u00e7\u00e3o de um angi\u00f3grafo de \u00faltima gera\u00e7\u00e3o, equipamento fundamental para a obten\u00e7\u00e3o de imagens detalhadas do sistema circulat\u00f3rio de forma minimamente invasiva.<\/p>\n\n\n\n<p>J\u00e1 o Hospital da Mulher ser\u00e1 beneficiado com a constru\u00e7\u00e3o de um novo ambulat\u00f3rio, no Largo de Roma, em espa\u00e7o onde funcionava o antigo Col\u00e9gio Estadual Ab\u00edlio C\u00e9sar Borges. Com or\u00e7amento de R$ 5,2 milh\u00f5es, a unidade ter\u00e1 35 consult\u00f3rios e salas para procedimentos, devendo ser entregue em at\u00e9 seis meses. Tamb\u00e9m foi assinada a autoriza\u00e7\u00e3o para o projeto de amplia\u00e7\u00e3o da UTI e do centro cir\u00fargico do hospital, que contar\u00e1 com mais 10 leitos de terapia intensiva e cinco salas cir\u00fargicas, alcan\u00e7ando R$ 5,6 milh\u00f5es de investimento.<\/p>\n\n\n\n<p>________________________________________________________________________________________________________________<\/p>\n\n\n<p class=\"wp-block-tag-cloud\"><a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/bahia\/\" class=\"tag-cloud-link tag-link-171 tag-link-position-1\" style=\"font-size: 17.333333333333pt;\" aria-label=\"Bahia (130 itens)\">Bahia<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/bolsonaro\/\" class=\"tag-cloud-link tag-link-112 tag-link-position-2\" style=\"font-size: 10.851851851852pt;\" aria-label=\"Bolsonaro (41 itens)\">Bolsonaro<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/brasil\/\" class=\"tag-cloud-link tag-link-335 tag-link-position-3\" style=\"font-size: 13.314814814815pt;\" aria-label=\"Brasil (63 itens)\">Brasil<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/camacari\/\" class=\"tag-cloud-link tag-link-435 tag-link-position-4\" style=\"font-size: 8.1296296296296pt;\" aria-label=\"Cama\u00e7ari (25 itens)\">Cama\u00e7ari<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/carnaval\/\" class=\"tag-cloud-link tag-link-508 tag-link-position-5\" style=\"font-size: 12.018518518519pt;\" aria-label=\"Carnaval (50 itens)\">Carnaval<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cbx\/\" class=\"tag-cloud-link tag-link-1602 tag-link-position-6\" style=\"font-size: 10.722222222222pt;\" aria-label=\"CBX (40 itens)\">CBX<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cidade-baixa\/\" class=\"tag-cloud-link tag-link-456 tag-link-position-7\" style=\"font-size: 9.4259259259259pt;\" aria-label=\"Cidade Baixa (31 itens)\">Cidade Baixa<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cinema\/\" class=\"tag-cloud-link tag-link-985 tag-link-position-8\" style=\"font-size: 10.462962962963pt;\" aria-label=\"Cinema (38 itens)\">Cinema<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cultura\/\" class=\"tag-cloud-link tag-link-231 tag-link-position-9\" style=\"font-size: 12.018518518519pt;\" aria-label=\"Cultura (50 itens)\">Cultura<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/drogas\/\" class=\"tag-cloud-link tag-link-165 tag-link-position-10\" style=\"font-size: 11.888888888889pt;\" aria-label=\"Drogas (49 itens)\">Drogas<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/educacao\/\" class=\"tag-cloud-link tag-link-228 tag-link-position-11\" style=\"font-size: 12.018518518519pt;\" aria-label=\"Educa\u00e7\u00e3o (50 itens)\">Educa\u00e7\u00e3o<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ensino\/\" class=\"tag-cloud-link tag-link-233 tag-link-position-12\" style=\"font-size: 10.722222222222pt;\" aria-label=\"Ensino (40 itens)\">Ensino<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/escola\/\" class=\"tag-cloud-link tag-link-229 tag-link-position-13\" style=\"font-size: 9.5555555555556pt;\" aria-label=\"Escola (32 itens)\">Escola<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/eua\/\" class=\"tag-cloud-link tag-link-664 tag-link-position-14\" style=\"font-size: 11.5pt;\" aria-label=\"EUA (46 itens)\">EUA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/feira-de-santana\/\" class=\"tag-cloud-link tag-link-642 tag-link-position-15\" style=\"font-size: 8.6481481481481pt;\" aria-label=\"Feira de Santana (27 itens)\">Feira de Santana<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ficco\/\" class=\"tag-cloud-link tag-link-143 tag-link-position-16\" style=\"font-size: 8.6481481481481pt;\" aria-label=\"Ficco (27 itens)\">Ficco<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/folia\/\" class=\"tag-cloud-link tag-link-566 tag-link-position-17\" style=\"font-size: 8.3888888888889pt;\" aria-label=\"Folia (26 itens)\">Folia<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/futebol\/\" class=\"tag-cloud-link tag-link-40 tag-link-position-18\" style=\"font-size: 12.407407407407pt;\" aria-label=\"Futebol (54 itens)\">Futebol<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/homicidio\/\" class=\"tag-cloud-link tag-link-101 tag-link-position-19\" style=\"font-size: 10.074074074074pt;\" aria-label=\"Homic\u00eddio (35 itens)\">Homic\u00eddio<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/itapagipe\/\" class=\"tag-cloud-link tag-link-471 tag-link-position-20\" style=\"font-size: 9.5555555555556pt;\" aria-label=\"Itapagipe (32 itens)\">Itapagipe<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/itaparica\/\" class=\"tag-cloud-link tag-link-301 tag-link-position-21\" style=\"font-size: 9.1666666666667pt;\" aria-label=\"Itaparica (30 itens)\">Itaparica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/justica\/\" class=\"tag-cloud-link tag-link-361 tag-link-position-22\" style=\"font-size: 10.333333333333pt;\" aria-label=\"Justi\u00e7a (37 itens)\">Justi\u00e7a<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lauro-de-freitas\/\" class=\"tag-cloud-link tag-link-594 tag-link-position-23\" style=\"font-size: 17.462962962963pt;\" aria-label=\"Lauro de Freitas (134 itens)\">Lauro de Freitas<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lazer\/\" class=\"tag-cloud-link tag-link-568 tag-link-position-24\" style=\"font-size: 9.1666666666667pt;\" aria-label=\"Lazer (30 itens)\">Lazer<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lula\/\" class=\"tag-cloud-link tag-link-416 tag-link-position-25\" style=\"font-size: 11.759259259259pt;\" aria-label=\"Lula (48 itens)\">Lula<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/meio-ambiente\/\" class=\"tag-cloud-link tag-link-475 tag-link-position-26\" style=\"font-size: 12.407407407407pt;\" aria-label=\"Meio Ambiente (54 itens)\">Meio Ambiente<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/mobilidade\/\" class=\"tag-cloud-link tag-link-278 tag-link-position-27\" style=\"font-size: 13.314814814815pt;\" aria-label=\"Mobilidade (63 itens)\">Mobilidade<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/moradia\/\" class=\"tag-cloud-link tag-link-1740 tag-link-position-28\" style=\"font-size: 8pt;\" aria-label=\"Moradia (24 itens)\">Moradia<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/mulher\/\" class=\"tag-cloud-link tag-link-450 tag-link-position-29\" style=\"font-size: 12.925925925926pt;\" aria-label=\"mulher (59 itens)\">mulher<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/musica-2\/\" class=\"tag-cloud-link tag-link-747 tag-link-position-30\" style=\"font-size: 11.240740740741pt;\" aria-label=\"M\u00fasica (44 itens)\">M\u00fasica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/pcba\/\" class=\"tag-cloud-link tag-link-1332 tag-link-position-31\" style=\"font-size: 14.351851851852pt;\" aria-label=\"PCBA (77 itens)\">PCBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/pmba\/\" class=\"tag-cloud-link tag-link-53 tag-link-position-32\" style=\"font-size: 17.333333333333pt;\" aria-label=\"PMBA (130 itens)\">PMBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/policia-federal\/\" class=\"tag-cloud-link tag-link-620 tag-link-position-33\" style=\"font-size: 8.3888888888889pt;\" aria-label=\"Pol\u00edcia Federal (26 itens)\">Pol\u00edcia Federal<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/politica\/\" class=\"tag-cloud-link tag-link-495 tag-link-position-34\" style=\"font-size: 15.518518518519pt;\" aria-label=\"Pol\u00edtica (94 itens)\">Pol\u00edtica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/rio-de-janeiro\/\" class=\"tag-cloud-link tag-link-152 tag-link-position-35\" style=\"font-size: 9.6851851851852pt;\" aria-label=\"Rio de Janeiro (33 itens)\">Rio de Janeiro<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/salvador\/\" class=\"tag-cloud-link tag-link-125 tag-link-position-36\" style=\"font-size: 22pt;\" aria-label=\"Salvador (298 itens)\">Salvador<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/saude\/\" class=\"tag-cloud-link tag-link-42 tag-link-position-37\" style=\"font-size: 17.203703703704pt;\" aria-label=\"Sa\u00fade (128 itens)\">Sa\u00fade<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/seguranca\/\" class=\"tag-cloud-link tag-link-48 tag-link-position-38\" style=\"font-size: 8.6481481481481pt;\" aria-label=\"Seguran\u00e7a (27 itens)\">Seguran\u00e7a<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ssp-ba\/\" class=\"tag-cloud-link tag-link-1937 tag-link-position-39\" style=\"font-size: 9.1666666666667pt;\" aria-label=\"SSP-BA (30 itens)\">SSP-BA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/sspba\/\" class=\"tag-cloud-link tag-link-144 tag-link-position-40\" style=\"font-size: 10.462962962963pt;\" aria-label=\"SSPBA (38 itens)\">SSPBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/stf\/\" class=\"tag-cloud-link tag-link-68 tag-link-position-41\" style=\"font-size: 13.703703703704pt;\" aria-label=\"STF (68 itens)\">STF<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/sao-joao\/\" class=\"tag-cloud-link tag-link-1198 tag-link-position-42\" style=\"font-size: 9.5555555555556pt;\" aria-label=\"S\u00e3o Jo\u00e3o (32 itens)\">S\u00e3o Jo\u00e3o<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/transito-2\/\" class=\"tag-cloud-link tag-link-377 tag-link-position-43\" style=\"font-size: 8.1296296296296pt;\" aria-label=\"tr\u00e2nsito (25 itens)\">tr\u00e2nsito<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/turismo\/\" class=\"tag-cloud-link tag-link-225 tag-link-position-44\" style=\"font-size: 9.5555555555556pt;\" aria-label=\"Turismo (32 itens)\">Turismo<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/uruguai\/\" class=\"tag-cloud-link tag-link-323 tag-link-position-45\" style=\"font-size: 8.7777777777778pt;\" aria-label=\"Uruguai (28 itens)\">Uruguai<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente<\/p>\n","protected":false},"author":2,"featured_media":7287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,46],"tags":[609,125,42],"class_list":["post-7286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grande-salvador","category-saude","tag-cajazeiras","tag-salvador","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais<\/title>\n<meta name=\"description\" content=\"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais\" \/>\n<meta property=\"og:description\" content=\"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicar Mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-30T16:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T19:50:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicar Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:site\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicar Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/\"},\"author\":{\"name\":\"Comunicar Mais\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"headline\":\"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o\",\"datePublished\":\"2025-03-30T16:34:00+00:00\",\"dateModified\":\"2025-03-30T19:50:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/\"},\"wordCount\":936,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg\",\"keywords\":[\"Cajazeiras\",\"Salvador\",\"Sa\u00fade\"],\"articleSection\":[\"Grande Salvador\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/\",\"name\":\"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg\",\"datePublished\":\"2025-03-30T16:34:00+00:00\",\"dateModified\":\"2025-03-30T19:50:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"description\":\"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2025\\\/03\\\/30\\\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"name\":\"Comunicar Mais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\",\"name\":\"Comunicar Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"caption\":\"Comunicar Mais\"},\"description\":\"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.\",\"sameAs\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"https:\\\/\\\/www.facebook.com\\\/comunicarmais\\\/\",\"https:\\\/\\\/www.instagram.com\\\/comunicarmaisba\\\/\",\"https:\\\/\\\/x.com\\\/ComunicarmaisBA\"],\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/author\\\/gerenciador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais","description":"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/","og_locale":"pt_BR","og_type":"article","og_title":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais","og_description":"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente","og_url":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/","og_site_name":"Comunicar Mais","article_publisher":"https:\/\/www.facebook.com\/comunicarmais\/","article_author":"https:\/\/www.facebook.com\/comunicarmais\/","article_published_time":"2025-03-30T16:34:00+00:00","article_modified_time":"2025-03-30T19:50:18+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg","type":"image\/jpeg"}],"author":"Comunicar Mais","twitter_card":"summary_large_image","twitter_creator":"@ComunicarmaisBA","twitter_site":"@ComunicarmaisBA","twitter_misc":{"Escrito por":"Comunicar Mais","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#article","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/"},"author":{"name":"Comunicar Mais","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"headline":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o","datePublished":"2025-03-30T16:34:00+00:00","dateModified":"2025-03-30T19:50:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/"},"wordCount":936,"commentCount":0,"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg","keywords":["Cajazeiras","Salvador","Sa\u00fade"],"articleSection":["Grande Salvador","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/","url":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/","name":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o - Comunicar Mais","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#primaryimage"},"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg","datePublished":"2025-03-30T16:34:00+00:00","dateModified":"2025-03-30T19:50:18+00:00","author":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"description":"Dentre os servi\u00e7os oferecidos est\u00e3o exames laboratoriais, ultrassonografia, eletrocardiograma, preventivo, tratamento odontol\u00f3gico e oftalmol\u00f3gico, consultas com nutricionista e oftalmologista, al\u00e9m de cirurgias de catarata e limpeza de lente","breadcrumb":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#primaryimage","url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg","contentUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-30-at-13.00.50.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.comunicarmais.com.br\/site\/2025\/03\/30\/governador-visita-feira-saude-mais-perto-em-cajazeiras-e-entrega-ambulancias-para-unidades-de-saude-da-regiao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comunicarmais.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Governador visita Feira Sa\u00fade Mais Perto, em Cajazeiras, e entrega ambul\u00e2ncias para unidades de sa\u00fade da regi\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.comunicarmais.com.br\/site\/#website","url":"https:\/\/www.comunicarmais.com.br\/site\/","name":"Comunicar Mais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comunicarmais.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284","name":"Comunicar Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","caption":"Comunicar Mais"},"description":"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.","sameAs":["https:\/\/www.comunicarmais.com.br\/site\/","https:\/\/www.facebook.com\/comunicarmais\/","https:\/\/www.instagram.com\/comunicarmaisba\/","https:\/\/x.com\/ComunicarmaisBA"],"url":"https:\/\/www.comunicarmais.com.br\/site\/author\/gerenciador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/7286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/comments?post=7286"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/7286\/revisions"}],"predecessor-version":[{"id":7292,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/7286\/revisions\/7292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media\/7287"}],"wp:attachment":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media?parent=7286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/categories?post=7286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/tags?post=7286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}