{"id":544,"date":"2024-01-03T12:15:00","date_gmt":"2024-01-03T15:15:00","guid":{"rendered":"https:\/\/www.comunicarmais.com.br\/site\/?p=544"},"modified":"2024-01-03T16:42:33","modified_gmt":"2024-01-03T19:42:33","slug":"meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles","status":"publish","type":"post","link":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/","title":{"rendered":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles"},"content":{"rendered":"\n<p><strong>Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas<\/strong> <strong>n\u00e3o \u00e9 descartado<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1171\" height=\"578\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg\" alt=\"\" class=\"wp-image-545 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg 1171w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar-1024x505.jpg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar-768x379.jpg 768w\" data-sizes=\"(max-width: 1171px) 100vw, 1171px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1171px; --smush-placeholder-aspect-ratio: 1171\/578;\" \/><figcaption class=\"wp-element-caption\">Est\u00e3o previstas chuvas entre 30 e 60 mil\u00edmetros (mm\/h) ou 50 e 100 mm\/dia <em>(Foto: Ag\u00eancia Brasil)<\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Ag\u00eancia Brasil &#8211; <\/strong>O Instituto Nacional de Meteorologia (Inmet) emitiu nesta quarta-feira (3) um alerta de chuvas intensas para o Distrito Federal (DF). Segundo o \u00f3rg\u00e3o, o aviso segue at\u00e9 esta quinta-feira (4), com possibilidade de se estender pelos pr\u00f3ximos dias.<\/p>\n\n\n\n<p>Est\u00e3o previstas chuvas entre 30 e 60 mil\u00edmetros (mm\/h) ou 50 e 100 mm\/dia, com ventos intensos que podem variar entre 60 a 100 km\/h. H\u00e1 ainda o risco de corte de energia el\u00e9trica, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas.<\/p>\n\n\n\n<p>Al\u00e9m do Distrito Federal, o alerta tamb\u00e9m vale para estados das regi\u00f5es Norte, Centro-Oeste, Sudeste e Nordeste. O alerta abrange, tamb\u00e9m, partes dos estados de Goi\u00e1s e Mato Grosso, no Centro-Oeste; da Bahia, Cear\u00e1, Maranh\u00e3o, Pernambuco e Piau\u00ed, no Nordeste; Par\u00e1, Rond\u00f4nia e Tocantins, no Norte, e Minas Gerais e Esp\u00edrito Santo, no Sudeste.<\/p>\n\n\n\n<p>Instabilidade<br>Segundo Her\u00e1clio Alves, meteorologista do Inmet, o aviso n\u00e3o significa necessariamente a ocorr\u00eancia de chuvas intensas em todas as regi\u00f5es. Ele lembra que o quadro de instabilidade \u00e9 t\u00edpico do ver\u00e3o e se deve a atua\u00e7\u00e3o da zona de converg\u00eancia do Atl\u00e2ntico Sul, que passa pelas regi\u00f5es Norte, Centro-Oeste e Sudeste. Esse canal, que mant\u00e9m a umidade nessa regi\u00e3o, deve permanecer atuante nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p>\u201cToda essa regi\u00e3o est\u00e1 com bastante instabilidade nos \u00faltimos dois dias com chuvas em v\u00e1rios locais. At\u00e9 os pr\u00f3ximos dias, com a perman\u00eancia das chuvas, provavelmente devemos manter esse aviso de chuvas intensas\u201d, informou o meteorologista \u00e0 Ag\u00eancia Brasil.<\/p>\n\n\n\n<p>Segundo o Inmet, a orienta\u00e7\u00e3o nessas situa\u00e7\u00f5es \u00e9 para, em caso de rajada de ventos, n\u00e3o se abrigar sob \u00e1rvores, pois h\u00e1 risco de descarga el\u00e9trica; n\u00e3o estacionar ve\u00edculos perto de torres de transmiss\u00e3o de energia e placas de propaganda; e, se poss\u00edvel, desligar aparelhos el\u00e9tricos e quadro geral de energia.<\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado<\/p>\n","protected":false},"author":2,"featured_media":545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[306,98],"class_list":["post-544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-meteorologia","tag-temporais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais<\/title>\n<meta name=\"description\" content=\"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais\" \/>\n<meta property=\"og:description\" content=\"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicar Mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-03T15:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T19:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1171\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicar Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:site\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicar Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/\"},\"author\":{\"name\":\"Comunicar Mais\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"headline\":\"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles\",\"datePublished\":\"2024-01-03T15:15:00+00:00\",\"dateModified\":\"2024-01-03T19:42:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/\"},\"wordCount\":374,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Capturar.jpg\",\"keywords\":[\"Meteorologia\",\"temporais\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/\",\"name\":\"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Capturar.jpg\",\"datePublished\":\"2024-01-03T15:15:00+00:00\",\"dateModified\":\"2024-01-03T19:42:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"description\":\"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Capturar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Capturar.jpg\",\"width\":1171,\"height\":578,\"caption\":\"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/01\\\/03\\\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"name\":\"Comunicar Mais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\",\"name\":\"Comunicar Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"caption\":\"Comunicar Mais\"},\"description\":\"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.\",\"sameAs\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"https:\\\/\\\/www.facebook.com\\\/comunicarmais\\\/\",\"https:\\\/\\\/www.instagram.com\\\/comunicarmaisba\\\/\",\"https:\\\/\\\/x.com\\\/ComunicarmaisBA\"],\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/author\\\/gerenciador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais","description":"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/","og_locale":"pt_BR","og_type":"article","og_title":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais","og_description":"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado","og_url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/","og_site_name":"Comunicar Mais","article_publisher":"https:\/\/www.facebook.com\/comunicarmais\/","article_author":"https:\/\/www.facebook.com\/comunicarmais\/","article_published_time":"2024-01-03T15:15:00+00:00","article_modified_time":"2024-01-03T19:42:33+00:00","og_image":[{"width":1171,"height":578,"url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg","type":"image\/jpeg"}],"author":"Comunicar Mais","twitter_card":"summary_large_image","twitter_creator":"@ComunicarmaisBA","twitter_site":"@ComunicarmaisBA","twitter_misc":{"Escrito por":"Comunicar Mais","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#article","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/"},"author":{"name":"Comunicar Mais","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"headline":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles","datePublished":"2024-01-03T15:15:00+00:00","dateModified":"2024-01-03T19:42:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/"},"wordCount":374,"commentCount":0,"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg","keywords":["Meteorologia","temporais"],"articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/","url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/","name":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles - Comunicar Mais","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#primaryimage"},"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg","datePublished":"2024-01-03T15:15:00+00:00","dateModified":"2024-01-03T19:42:33+00:00","author":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"description":"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado","breadcrumb":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#primaryimage","url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg","contentUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/01\/Capturar.jpg","width":1171,"height":578,"caption":"Risco de apag\u00f5es, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas n\u00e3o \u00e9 descartado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/01\/03\/meteorologia-alerta-para-chuvas-intensas-em-12-estados-bahia-e-um-deles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comunicarmais.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Meteorologia alerta para chuvas intensas em 12 estados; Bahia \u00e9 um deles"}]},{"@type":"WebSite","@id":"https:\/\/www.comunicarmais.com.br\/site\/#website","url":"https:\/\/www.comunicarmais.com.br\/site\/","name":"Comunicar Mais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comunicarmais.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284","name":"Comunicar Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","caption":"Comunicar Mais"},"description":"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.","sameAs":["https:\/\/www.comunicarmais.com.br\/site\/","https:\/\/www.facebook.com\/comunicarmais\/","https:\/\/www.instagram.com\/comunicarmaisba\/","https:\/\/x.com\/ComunicarmaisBA"],"url":"https:\/\/www.comunicarmais.com.br\/site\/author\/gerenciador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":546,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/544\/revisions\/546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media\/545"}],"wp:attachment":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}