{"id":1503,"date":"2024-03-15T13:43:00","date_gmt":"2024-03-15T16:43:00","guid":{"rendered":"https:\/\/www.comunicarmais.com.br\/site\/?p=1503"},"modified":"2024-03-15T17:53:41","modified_gmt":"2024-03-15T20:53:41","slug":"ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe","status":"publish","type":"post","link":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/","title":{"rendered":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe"},"content":{"rendered":"\n<p><strong>Freire Gomes desestimulou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1169\" height=\"690\" data-src=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg\" alt=\"\" class=\"wp-image-1504 lazyload\" data-srcset=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg 1169w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero-1024x604.jpg 1024w, https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero-768x453.jpg 768w\" data-sizes=\"(max-width: 1169px) 100vw, 1169px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1169px; --smush-placeholder-aspect-ratio: 1169\/690;\" \/><\/figure>\n\n\n\n<p><strong>Ag\u00eancia Brasil &#8211; <\/strong>O tenente-brigadeiro do ar Carlos Almeida Baptista J\u00fanior, ex-comandante da Aeron\u00e1utica, disse em depoimento \u00e0 Pol\u00edcia Federal (PF) que o general Marco Antonio Freire Gomes, ex-comandante do Ex\u00e9rcito, amea\u00e7ou prender o ex-presidente Jair Bolsonaro caso levasse adiante uma tentativa de golpe de Estado.<\/p>\n\n\n\n<p>O depoimento foi dado no inqu\u00e9rito sobre uma trama golpista elaborada na c\u00fapula do governo de Bolsonaro. O sigilo sobre as declara\u00e7\u00f5es foi tirado nesta sexta-feira (15) pelo relator do caso no Supremo Tribunal Federal (STF), ministro Alexandre de Moraes. &#8220;Depois de o presidente da Rep\u00fablica, Jair Bolsonaro, aventar a hip\u00f3tese de atentar contra o regime democr\u00e1tico, por meio de alguns institutos previstos na Constitui\u00e7\u00e3o (GLO ou estado de defesa ou estado de s\u00edtio), o ent\u00e3o comandante do Ex\u00e9rcito, general Freire Gomes, afirmou que caso tentasse tal ato teria que prender o presidente da Rep\u00fablica\u201d, disse o ex-comandante da For\u00e7a A\u00e9rea Brasileira (FAB).<\/p>\n\n\n\n<p>Ainda segundo Baptista Jr, Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO).<\/p>\n\n\n\n<p>Segundo relat\u00f3rio da PF, Baptista Jr. disse que, em reuni\u00e3o com Bolsonaro, ele pr\u00f3prio deixou claro que se opunha a qualquer plano golpista e que n\u00e3o havia mais possiblidade do ent\u00e3o presidente permanecer no cargo. &#8220;Em outra reuni\u00e3o de comandantes das For\u00e7as com o ent\u00e3o presidente da Rep\u00fablica, o depoente deixou evidente a Jair Bolsonaro que n\u00e3o haveria qualquer hip\u00f3tese do ent\u00e3o presidente permanecer no poder ap\u00f3s o t\u00e9rmino do seu mandato. Que deixou claro ao ent\u00e3o presidente Jair Bolsonaro que n\u00e3o aceitaria qualquer tentativa de ruptura institucional para mant\u00ea-lo no poder\u201d, diz o relat\u00f3rio da PF sobre o depoimento.<\/p>\n\n\n\n<p>Carlos-Almeida Baptista J\u00fanior acrescentou ter participado de cinco ou seis reuni\u00f5es com Bolsonaro e os outros comandantes das For\u00e7as Armadas, ap\u00f3s a elei\u00e7\u00e3o presidencial de 2022. O tenente-brigadeiro disse ter alertado o presidente que n\u00e3o havia fraude nas urnas eletr\u00f4nicas, tese defendida pelos apoiadores de Bolsonaro para justificar a perman\u00eancia no poder.<\/p>\n\n\n\n<p>Segundo contou a PF, o ex-comandante disse que Bolsonaro era atualizado sobre os trabalhos do representante da Aeron\u00e1utica na Comiss\u00e3o de Fiscaliza\u00e7\u00e3o das Elei\u00e7\u00f5es, sendo avisado que nenhuma fraude havia sido encontrada na vota\u00e7\u00e3o do primeiro ou do segundo turno.<\/p>\n\n\n\n<p>O \u00fanico que \u201ccolocou as tropas \u00e0 disposi\u00e7\u00e3o\u201d de Bolsonaro, de acordo com Baptista Jr., foi o almirante Almir Garnier, ex-comandante da Marinha.<\/p>\n\n\n\n<p>Indagado sobre quando lhe foi apresentada uma minuta para a decreta\u00e7\u00e3o de golpe, Baptista Jr. disse que o documento foi exibido aos comandantes das For\u00e7as Armadas em reuni\u00e3o no Minist\u00e9rio da Defesa, em 14 de dezembro de 2022, pelo ent\u00e3o titular da pasta, general Paulo S\u00e9rgio de Oliveira.<\/p>\n\n\n\n<p>De acordo com o relato do ex-comandante da Aeron\u00e1utica, Oliveira colocou a minuta sobre uma mesa e disse que gostaria de apresentar o documento \u201cpara conhecimento e revis\u00e3o\u201d.<\/p>\n\n\n\n<p>\u201cQue o depoente entendeu que haveria uma ordem que impediria a posse do novo governo eleito; Que, diante disso, o depoente disse ao Ministro da Defesa que n\u00e3o admitiria sequer receber esse documento; Que a For\u00e7a A\u00e9rea n\u00e3o admitiria tal hip\u00f3tese (Golpe de Estado)\u201d, diz a transcri\u00e7\u00e3o do depoimento de Baptista Jr, feita pela PF.<\/p>\n\n\n\n<p>Pelo depoimento do ex-comandante da FAB, o ex-comandante do Ex\u00e9rcito, Freire Gomes, \u201cexpressou que tamb\u00e9m n\u00e3o concordaria com a hip\u00f3tese de analisar o conte\u00fado da minuta\u201d. Baptista Jr. disse ter se retirado da sala em seguida, mas acrescentou que, enquanto esteve na reuni\u00e3o, o ex-comandante da Marinha, Almir Garnier, \u201cn\u00e3o expressou qualquer rea\u00e7\u00e3o contr\u00e1ria ao conte\u00fado da minuta\u201d.<\/p>\n\n\n\n<p>Baptista Jr. disse ainda aos investigadores que, ao comunicar o ent\u00e3o ministro-chefe do Gabinete de Seguran\u00e7a Institucional (GSI), general Augusto Heleno, que n\u00e3o aderiria a nenhuma &#8220;virada de mesa&#8221;, este teria ficado &#8220;at\u00f4nito&#8221; com a afirma\u00e7\u00e3o.<\/p>\n\n\n<p class=\"wp-block-tag-cloud\"><a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/bahia\/\" class=\"tag-cloud-link tag-link-171 tag-link-position-1\" style=\"font-size: 17.641509433962pt;\" aria-label=\"Bahia (117 itens)\">Bahia<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/bolsonaro\/\" class=\"tag-cloud-link tag-link-112 tag-link-position-2\" style=\"font-size: 11.433962264151pt;\" aria-label=\"Bolsonaro (39 itens)\">Bolsonaro<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/brasil\/\" class=\"tag-cloud-link tag-link-335 tag-link-position-3\" style=\"font-size: 12.88679245283pt;\" aria-label=\"Brasil (50 itens)\">Brasil<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/camacari\/\" class=\"tag-cloud-link tag-link-435 tag-link-position-4\" style=\"font-size: 8.7924528301887pt;\" aria-label=\"Cama\u00e7ari (24 itens)\">Cama\u00e7ari<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/carnaval\/\" class=\"tag-cloud-link tag-link-508 tag-link-position-5\" style=\"font-size: 12.754716981132pt;\" aria-label=\"Carnaval (49 itens)\">Carnaval<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cbx\/\" class=\"tag-cloud-link tag-link-1602 tag-link-position-6\" style=\"font-size: 11.301886792453pt;\" aria-label=\"CBX (38 itens)\">CBX<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cidade-baixa\/\" class=\"tag-cloud-link tag-link-456 tag-link-position-7\" style=\"font-size: 9.8490566037736pt;\" aria-label=\"Cidade Baixa (29 itens)\">Cidade Baixa<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cinema\/\" class=\"tag-cloud-link tag-link-985 tag-link-position-8\" style=\"font-size: 11.169811320755pt;\" aria-label=\"Cinema (37 itens)\">Cinema<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/cultura\/\" class=\"tag-cloud-link tag-link-231 tag-link-position-9\" style=\"font-size: 12.22641509434pt;\" aria-label=\"Cultura (45 itens)\">Cultura<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/drogas\/\" class=\"tag-cloud-link tag-link-165 tag-link-position-10\" style=\"font-size: 12.622641509434pt;\" aria-label=\"Drogas (48 itens)\">Drogas<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/educacao\/\" class=\"tag-cloud-link tag-link-228 tag-link-position-11\" style=\"font-size: 12.622641509434pt;\" aria-label=\"Educa\u00e7\u00e3o (48 itens)\">Educa\u00e7\u00e3o<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ensino\/\" class=\"tag-cloud-link tag-link-233 tag-link-position-12\" style=\"font-size: 10.509433962264pt;\" aria-label=\"Ensino (33 itens)\">Ensino<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/escola\/\" class=\"tag-cloud-link tag-link-229 tag-link-position-13\" style=\"font-size: 9.5849056603774pt;\" aria-label=\"Escola (28 itens)\">Escola<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/eua\/\" class=\"tag-cloud-link tag-link-664 tag-link-position-14\" style=\"font-size: 11.962264150943pt;\" aria-label=\"EUA (43 itens)\">EUA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/feira-de-santana\/\" class=\"tag-cloud-link tag-link-642 tag-link-position-15\" style=\"font-size: 9.188679245283pt;\" aria-label=\"Feira de Santana (26 itens)\">Feira de Santana<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ficco\/\" class=\"tag-cloud-link tag-link-143 tag-link-position-16\" style=\"font-size: 9.188679245283pt;\" aria-label=\"Ficco (26 itens)\">Ficco<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/folia\/\" class=\"tag-cloud-link tag-link-566 tag-link-position-17\" style=\"font-size: 9.188679245283pt;\" aria-label=\"Folia (26 itens)\">Folia<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/futebol\/\" class=\"tag-cloud-link tag-link-40 tag-link-position-18\" style=\"font-size: 12.88679245283pt;\" aria-label=\"Futebol (50 itens)\">Futebol<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/homicidio\/\" class=\"tag-cloud-link tag-link-101 tag-link-position-19\" style=\"font-size: 10.641509433962pt;\" aria-label=\"Homic\u00eddio (34 itens)\">Homic\u00eddio<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/itapagipe\/\" class=\"tag-cloud-link tag-link-471 tag-link-position-20\" style=\"font-size: 9.9811320754717pt;\" aria-label=\"Itapagipe (30 itens)\">Itapagipe<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/itaparica\/\" class=\"tag-cloud-link tag-link-301 tag-link-position-21\" style=\"font-size: 8.5283018867925pt;\" aria-label=\"Itaparica (23 itens)\">Itaparica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/jeronimo-rodrigues\/\" class=\"tag-cloud-link tag-link-668 tag-link-position-22\" style=\"font-size: 8.2641509433962pt;\" aria-label=\"Jer\u00f4nimo Rodrigues (22 itens)\">Jer\u00f4nimo Rodrigues<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/justica\/\" class=\"tag-cloud-link tag-link-361 tag-link-position-23\" style=\"font-size: 10.641509433962pt;\" aria-label=\"Justi\u00e7a (34 itens)\">Justi\u00e7a<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lauro-de-freitas\/\" class=\"tag-cloud-link tag-link-594 tag-link-position-24\" style=\"font-size: 17.905660377358pt;\" aria-label=\"Lauro de Freitas (123 itens)\">Lauro de Freitas<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lazer\/\" class=\"tag-cloud-link tag-link-568 tag-link-position-25\" style=\"font-size: 9.4528301886792pt;\" aria-label=\"Lazer (27 itens)\">Lazer<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/lula\/\" class=\"tag-cloud-link tag-link-416 tag-link-position-26\" style=\"font-size: 12.094339622642pt;\" aria-label=\"Lula (44 itens)\">Lula<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/meio-ambiente\/\" class=\"tag-cloud-link tag-link-475 tag-link-position-27\" style=\"font-size: 12.358490566038pt;\" aria-label=\"Meio Ambiente (46 itens)\">Meio Ambiente<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/mobilidade\/\" class=\"tag-cloud-link tag-link-278 tag-link-position-28\" style=\"font-size: 13.679245283019pt;\" aria-label=\"Mobilidade (58 itens)\">Mobilidade<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/mulher\/\" class=\"tag-cloud-link tag-link-450 tag-link-position-29\" style=\"font-size: 13.283018867925pt;\" aria-label=\"mulher (54 itens)\">mulher<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/musica-2\/\" class=\"tag-cloud-link tag-link-747 tag-link-position-30\" style=\"font-size: 12.094339622642pt;\" aria-label=\"M\u00fasica (44 itens)\">M\u00fasica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/pcba\/\" class=\"tag-cloud-link tag-link-1332 tag-link-position-31\" style=\"font-size: 15pt;\" aria-label=\"PCBA (73 itens)\">PCBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/pmba\/\" class=\"tag-cloud-link tag-link-53 tag-link-position-32\" style=\"font-size: 18.037735849057pt;\" aria-label=\"PMBA (124 itens)\">PMBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/policia-federal\/\" class=\"tag-cloud-link tag-link-620 tag-link-position-33\" style=\"font-size: 8.9245283018868pt;\" aria-label=\"Pol\u00edcia Federal (25 itens)\">Pol\u00edcia Federal<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/politica\/\" class=\"tag-cloud-link tag-link-495 tag-link-position-34\" style=\"font-size: 16.188679245283pt;\" aria-label=\"Pol\u00edtica (91 itens)\">Pol\u00edtica<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/rio-de-janeiro\/\" class=\"tag-cloud-link tag-link-152 tag-link-position-35\" style=\"font-size: 9.8490566037736pt;\" aria-label=\"Rio de Janeiro (29 itens)\">Rio de Janeiro<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/salvador\/\" class=\"tag-cloud-link tag-link-125 tag-link-position-36\" style=\"font-size: 22pt;\" aria-label=\"Salvador (248 itens)\">Salvador<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/saude\/\" class=\"tag-cloud-link tag-link-42 tag-link-position-37\" style=\"font-size: 17.77358490566pt;\" aria-label=\"Sa\u00fade (118 itens)\">Sa\u00fade<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/seguranca\/\" class=\"tag-cloud-link tag-link-48 tag-link-position-38\" style=\"font-size: 9.188679245283pt;\" aria-label=\"Seguran\u00e7a (26 itens)\">Seguran\u00e7a<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/ssp-ba\/\" class=\"tag-cloud-link tag-link-1937 tag-link-position-39\" style=\"font-size: 9.188679245283pt;\" aria-label=\"SSP-BA (26 itens)\">SSP-BA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/sspba\/\" class=\"tag-cloud-link tag-link-144 tag-link-position-40\" style=\"font-size: 11.301886792453pt;\" aria-label=\"SSPBA (38 itens)\">SSPBA<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/stf\/\" class=\"tag-cloud-link tag-link-68 tag-link-position-41\" style=\"font-size: 14.207547169811pt;\" aria-label=\"STF (64 itens)\">STF<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/sao-paulo\/\" class=\"tag-cloud-link tag-link-612 tag-link-position-42\" style=\"font-size: 8pt;\" aria-label=\"S\u00e3o Paulo (21 itens)\">S\u00e3o Paulo<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/transito-2\/\" class=\"tag-cloud-link tag-link-377 tag-link-position-43\" style=\"font-size: 8.2641509433962pt;\" aria-label=\"tr\u00e2nsito (22 itens)\">tr\u00e2nsito<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/turismo\/\" class=\"tag-cloud-link tag-link-225 tag-link-position-44\" style=\"font-size: 9.9811320754717pt;\" aria-label=\"Turismo (30 itens)\">Turismo<\/a>\n<a href=\"https:\/\/www.comunicarmais.com.br\/site\/tag\/uruguai\/\" class=\"tag-cloud-link tag-link-323 tag-link-position-45\" style=\"font-size: 9.5849056603774pt;\" aria-label=\"Uruguai (28 itens)\">Uruguai<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe<\/p>\n","protected":false},"author":2,"featured_media":1504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[112,758,759],"class_list":["post-1503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-bolsonaro","tag-exercito","tag-fab"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais<\/title>\n<meta name=\"description\" content=\"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais\" \/>\n<meta property=\"og:description\" content=\"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/\" \/>\n<meta property=\"og:site_name\" content=\"Comunicar Mais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/comunicarmais\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T16:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T20:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1169\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicar Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:site\" content=\"@ComunicarmaisBA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicar Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/\"},\"author\":{\"name\":\"Comunicar Mais\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"headline\":\"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe\",\"datePublished\":\"2024-03-15T16:43:00+00:00\",\"dateModified\":\"2024-03-15T20:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/\"},\"wordCount\":754,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aero.jpg\",\"keywords\":[\"Bolsonaro\",\"Ex\u00e9rcito\",\"FAB\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/\",\"name\":\"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aero.jpg\",\"datePublished\":\"2024-03-15T16:43:00+00:00\",\"dateModified\":\"2024-03-15T20:53:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\"},\"description\":\"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aero.jpg\",\"width\":1169,\"height\":690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/2024\\\/03\\\/15\\\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"name\":\"Comunicar Mais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/#\\\/schema\\\/person\\\/712f7b6b25b644e4a91c4173674cf284\",\"name\":\"Comunicar Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g\",\"caption\":\"Comunicar Mais\"},\"description\":\"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.\",\"sameAs\":[\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/\",\"https:\\\/\\\/www.facebook.com\\\/comunicarmais\\\/\",\"https:\\\/\\\/www.instagram.com\\\/comunicarmaisba\\\/\",\"https:\\\/\\\/x.com\\\/ComunicarmaisBA\"],\"url\":\"https:\\\/\\\/www.comunicarmais.com.br\\\/site\\\/author\\\/gerenciador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais","description":"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/","og_locale":"pt_BR","og_type":"article","og_title":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais","og_description":"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)","og_url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/","og_site_name":"Comunicar Mais","article_publisher":"https:\/\/www.facebook.com\/comunicarmais\/","article_author":"https:\/\/www.facebook.com\/comunicarmais\/","article_published_time":"2024-03-15T16:43:00+00:00","article_modified_time":"2024-03-15T20:53:41+00:00","og_image":[{"width":1169,"height":690,"url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg","type":"image\/jpeg"}],"author":"Comunicar Mais","twitter_card":"summary_large_image","twitter_creator":"@ComunicarmaisBA","twitter_site":"@ComunicarmaisBA","twitter_misc":{"Escrito por":"Comunicar Mais","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#article","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/"},"author":{"name":"Comunicar Mais","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"headline":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe","datePublished":"2024-03-15T16:43:00+00:00","dateModified":"2024-03-15T20:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/"},"wordCount":754,"commentCount":0,"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg","keywords":["Bolsonaro","Ex\u00e9rcito","FAB"],"articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/","url":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/","name":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe - Comunicar Mais","isPartOf":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#primaryimage"},"image":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg","datePublished":"2024-03-15T16:43:00+00:00","dateModified":"2024-03-15T20:53:41+00:00","author":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284"},"description":"Freire Gomes desincentivou Bolsonaro a se valer de teses jur\u00eddicas estranhas para dar um golpe, como a decreta\u00e7\u00e3o de estado de s\u00edtio, estado de defesa, ou Garantia da Lei e da Ordem (GLO)","breadcrumb":{"@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#primaryimage","url":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg","contentUrl":"https:\/\/www.comunicarmais.com.br\/site\/wp-content\/uploads\/2024\/03\/aero.jpg","width":1169,"height":690},{"@type":"BreadcrumbList","@id":"https:\/\/www.comunicarmais.com.br\/site\/2024\/03\/15\/ex-comandante-do-exercito-ameacou-prender-bolsonaro-medida-seria-tomada-caso-ex-presidente-seguisse-com-tentativa-de-golpe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comunicarmais.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Ex-comandante do Ex\u00e9rcito amea\u00e7ou prender Bolsonaro caso ex-presidente seguisse com tentativa de golpe"}]},{"@type":"WebSite","@id":"https:\/\/www.comunicarmais.com.br\/site\/#website","url":"https:\/\/www.comunicarmais.com.br\/site\/","name":"Comunicar Mais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comunicarmais.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.comunicarmais.com.br\/site\/#\/schema\/person\/712f7b6b25b644e4a91c4173674cf284","name":"Comunicar Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9803218072e2c0dc265d3d787b54c2c33325e79f79732707fddfbf1efd82c678?s=96&d=mm&r=g","caption":"Comunicar Mais"},"description":"Deixe as ideologias com os ide\u00f3logos. Noticiamos fatos, n\u00e3o brigamos com eles. Aqui, voc\u00ea fica bem informado do que acontece no seu bairro e no mundo. Informar com \u00e9tica e responsabilidade s\u00e3o as bandeiras do Comunicarmais.","sameAs":["https:\/\/www.comunicarmais.com.br\/site\/","https:\/\/www.facebook.com\/comunicarmais\/","https:\/\/www.instagram.com\/comunicarmaisba\/","https:\/\/x.com\/ComunicarmaisBA"],"url":"https:\/\/www.comunicarmais.com.br\/site\/author\/gerenciador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/comments?post=1503"}],"version-history":[{"count":3,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/1503\/revisions"}],"predecessor-version":[{"id":1508,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/posts\/1503\/revisions\/1508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media\/1504"}],"wp:attachment":[{"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/categories?post=1503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicarmais.com.br\/site\/wp-json\/wp\/v2\/tags?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}